{"id":12670,"date":"2021-08-12T18:14:16","date_gmt":"2021-08-13T01:14:16","guid":{"rendered":"https:\/\/mambabudds.co\/canada-wide\/product\/pink-death\/"},"modified":"2026-08-15T02:55:51","modified_gmt":"2026-08-15T09:55:51","slug":"mort-rose","status":"publish","type":"product","link":"https:\/\/mambabudds.co\/canada-wide\/fr\/product\/pink-death\/","title":{"rendered":"Pink Death (AAAA)"},"content":{"rendered":"<p style=\"text-align: center;\">Pink Death est une vari\u00e9t\u00e9 indica qui procure aux utilisateurs un high puissant qui frappe l&#039;esprit et le corps, qui provient du croisement de Bubba Kush et de Pink Kush. D\u00e8s que vous prenez votre premi\u00e8re bouff\u00e9e de cette fleur, vous sentirez l&#039;effet imm\u00e9diatement. Le magnifique stone lourd laisse les utilisateurs d\u00e9tendus et d\u00e9tendus. Nous sugg\u00e9rons aux consommateurs de s&#039;en tenir \u00e0 cette fleur la nuit pour ses effets s\u00e9datifs qui laissent la plupart des utilisateurs coinc\u00e9s sur leur canap\u00e9 devant la t\u00e9l\u00e9vision ou perdus dans le r\u00e9frig\u00e9rateur. Gr\u00e2ce \u00e0 ses effets puissants, toute personne souffrant de sympt\u00f4mes de douleur, de stress, de d\u00e9pression ou d&#039;anxi\u00e9t\u00e9 ressentira un soulagement instantan\u00e9. Allez-y doucement avec celle-ci et essayez de ne pas surdoser, sinon vous risquez de vous endormir.<\/p>","protected":false},"excerpt":{"rendered":"<p style=\"text-align: center;\">Pink Death est une vari\u00e9t\u00e9 indica qui procure aux utilisateurs un high puissant qui frappe l&#039;esprit et le corps, qui provient du croisement de Bubba Kush et de Pink Kush. D\u00e8s que vous prenez votre premi\u00e8re bouff\u00e9e de cette fleur, vous sentirez l&#039;effet imm\u00e9diatement. Le magnifique stone lourd laisse les utilisateurs d\u00e9tendus et d\u00e9tendus. Nous sugg\u00e9rons aux consommateurs de s&#039;en tenir \u00e0 cette fleur la nuit pour ses effets s\u00e9datifs qui laissent la plupart des utilisateurs coinc\u00e9s sur leur canap\u00e9 devant la t\u00e9l\u00e9vision ou perdus dans le r\u00e9frig\u00e9rateur. Gr\u00e2ce \u00e0 ses effets puissants, toute personne souffrant de sympt\u00f4mes de douleur, de stress, de d\u00e9pression ou d&#039;anxi\u00e9t\u00e9 ressentira un soulagement instantan\u00e9. Allez-y doucement avec celle-ci et essayez de ne pas surdoser, sinon vous risquez de vous endormir.<\/p>","protected":false},"featured_media":12669,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[53,39,41],"product_tag":[],"class_list":["post-12670","product","type-product","status-publish","has-post-thumbnail","product_cat-aaaa","product_cat-flowers","product_cat-indica","tm-has-options","first","instock","taxable","shipping-taxable","purchasable","product-type-variable"],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/mambabudds.co\/canada-wide\/fr\/wp-json\/wp\/v2\/product\/12670","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mambabudds.co\/canada-wide\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/mambabudds.co\/canada-wide\/fr\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/mambabudds.co\/canada-wide\/fr\/wp-json\/wp\/v2\/comments?post=12670"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mambabudds.co\/canada-wide\/fr\/wp-json\/wp\/v2\/media\/12669"}],"wp:attachment":[{"href":"https:\/\/mambabudds.co\/canada-wide\/fr\/wp-json\/wp\/v2\/media?parent=12670"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/mambabudds.co\/canada-wide\/fr\/wp-json\/wp\/v2\/product_brand?post=12670"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/mambabudds.co\/canada-wide\/fr\/wp-json\/wp\/v2\/product_cat?post=12670"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/mambabudds.co\/canada-wide\/fr\/wp-json\/wp\/v2\/product_tag?post=12670"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}